{"id":6940,"date":"2025-06-30T13:41:37","date_gmt":"2025-06-30T11:41:37","guid":{"rendered":"http:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/?p=6940"},"modified":"2025-06-30T13:41:38","modified_gmt":"2025-06-30T11:41:38","slug":"ateliers-fresque-du-climat-au-lycee-nodier","status":"publish","type":"post","link":"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/ateliers-fresque-du-climat-au-lycee-nodier\/","title":{"rendered":"Ateliers Fresque du Climat au lyc\u00e9e Nodier"},"content":{"rendered":"\n<p style=\"text-align: justify;\">Quatre groupes d&rsquo;\u00e9l\u00e8ves de Seconde ont pu participer en cette fin d&rsquo;ann\u00e9e \u00e0 un atelier de la Fresque du Climat, soit une trentaine d&rsquo;\u00e9l\u00e8ves. Ces ateliers ont \u00e9t\u00e9 anim\u00e9s par deux professeurs du lyc\u00e9e qui sont aussi animateurs de la Fresque.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;objectif est de permettre aux \u00e9l\u00e8ves de construire des fresques r\u00e9sumant les m\u00e9canismes du changement climatique. Pour cela, chaque groupe disposait de cartes \u00e0 organiser de fa\u00e7on logique, pour d\u00e9terminer les causes et les cons\u00e9quences du d\u00e9r\u00e8glement climatique. <br \/>Les donn\u00e9es inscrites sur ces cartes sont issues des derniers rapports du GIEC (groupe d\u2019experts intergouvernemental sur l\u2019\u00e9volution du climat).<\/p>\n<p style=\"text-align: justify;\">L\u2019atelier mobilise l\u2019intelligence collective et la dynamique du groupe pour sensibiliser les participants aux bouleversements climatiques. Son approche ludique et p\u00e9dagogique permet \u00e0 tous les publics de s\u2019approprier le sujet. Durant l\u2019atelier, les participants relient les liens de cause \u00e0 effets et int\u00e8grent les enjeux climatiques dans leur globalit\u00e9.<\/p>\n<p style=\"text-align: justify;\">Chaque atelier dure 3h.<br \/>Dans une premi\u00e8re \u00e9tape, les \u00e9l\u00e8ves, r\u00e9partis par \u00e9quipe ont d\u2019abord d\u00e9couvert les cartes puis ont r\u00e9fl\u00e9chi ensemble \u00e0 la fa\u00e7on de les relier afin de diff\u00e9rencier les causes et les cons\u00e9quences du changement climatique.<br \/>Dans une deuxi\u00e8me phase, faisant appel \u00e0 leur cr\u00e9ativit\u00e9, les \u00e9l\u00e8ves ont \u00e9t\u00e9 invit\u00e9 \u00e0 disposer ces cartes sur de grandes feuilles en papier de fa\u00e7on logique, en tra\u00e7ant les liens entre elles et en imaginant un titre et des illustrations, afin de s&rsquo;approprier v\u00e9ritablement leur fresque.<br \/>Enfin, une derni\u00e8re phase permet la discussion entre les participants.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"6942\" src=\"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/IMG_20250610_105255_727-768x1024.jpg\" alt=\"\" class=\"wp-image-6942\" srcset=\"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/IMG_20250610_105255_727-768x1024.jpg 768w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/IMG_20250610_105255_727-225x300.jpg 225w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/IMG_20250610_105255_727-113x150.jpg 113w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/IMG_20250610_105255_727.jpg 1125w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"6946\" src=\"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_080516607.MP_-1024x576.jpg\" alt=\"\" class=\"wp-image-6946\" srcset=\"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_080516607.MP_-1024x576.jpg 1024w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_080516607.MP_-300x169.jpg 300w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_080516607.MP_-768x432.jpg 768w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_080516607.MP_-150x84.jpg 150w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_080516607.MP_-250x141.jpg 250w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_080516607.MP_.jpg 1176w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"6941\" src=\"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_091226008-1024x576.jpg\" alt=\"\" class=\"wp-image-6941\" srcset=\"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_091226008-1024x576.jpg 1024w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_091226008-300x169.jpg 300w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_091226008-768x432.jpg 768w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_091226008-150x84.jpg 150w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_091226008-250x141.jpg 250w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_091226008.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"6943\" src=\"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_092210350-1024x576.jpg\" alt=\"\" class=\"wp-image-6943\" srcset=\"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_092210350-1024x576.jpg 1024w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_092210350-300x169.jpg 300w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_092210350-768x432.jpg 768w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_092210350-150x84.jpg 150w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_092210350-250x141.jpg 250w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_092210350.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"6944\" src=\"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_135944041-576x1024.jpg\" alt=\"\" class=\"wp-image-6944\" srcset=\"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_135944041-576x1024.jpg 576w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_135944041-169x300.jpg 169w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_135944041-768x1365.jpg 768w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_135944041-84x150.jpg 84w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_135944041.jpg 844w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"6945\" src=\"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_135955987-1024x576.jpg\" alt=\"\" class=\"wp-image-6945\" srcset=\"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_135955987-1024x576.jpg 1024w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_135955987-300x169.jpg 300w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_135955987-768x432.jpg 768w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_135955987-150x84.jpg 150w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_135955987-250x141.jpg 250w, https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-content\/uploads\/2025\/06\/PXL_20250610_135955987.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Quatre groupes d&rsquo;\u00e9l\u00e8ves de Seconde ont pu participer en cette fin d&rsquo;ann\u00e9e \u00e0 un atelier de la Fresque du Climat, soit une trentaine d&rsquo;\u00e9l\u00e8ves. Ces ateliers ont \u00e9t\u00e9 anim\u00e9s par\u2026<\/p>\n<p> <a class=\"continue-reading-link\" href=\"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/ateliers-fresque-du-climat-au-lycee-nodier\/\"><span>Lire la suite<\/span><i class=\"crycon-right-dir\"><\/i><\/a> <\/p>\n","protected":false},"author":110,"featured_media":6943,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[106,92,10,91,93],"tags":[210,187],"coauthors":[173],"class_list":["post-6940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-e3d","category-eleves","category-2nde","category-parents","category-personnels","tag-climat","tag-developpement-durable"],"views":830,"_links":{"self":[{"href":"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-json\/wp\/v2\/posts\/6940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-json\/wp\/v2\/users\/110"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=6940"}],"version-history":[{"count":3,"href":"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-json\/wp\/v2\/posts\/6940\/revisions"}],"predecessor-version":[{"id":6949,"href":"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-json\/wp\/v2\/posts\/6940\/revisions\/6949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-json\/wp\/v2\/media\/6943"}],"wp:attachment":[{"href":"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=6940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=6940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=6940"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.lycee-charles-nodier-ac-besancon.fr\/wordpress\/wp-json\/wp\/v2\/coauthors?post=6940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}